{"id":10735,"date":"2025-12-19T00:01:00","date_gmt":"2025-12-19T03:01:00","guid":{"rendered":"https:\/\/3260.com.ar\/web\/?p=10735"},"modified":"2025-12-18T23:10:11","modified_gmt":"2025-12-19T02:10:11","slug":"omar-faure-designado-como-secretario-de-ciencia-y-tecnologia-de-la-universidad-tecnologica-nacional","status":"publish","type":"post","link":"https:\/\/3260.com.ar\/web\/omar-faure-designado-como-secretario-de-ciencia-y-tecnologia-de-la-universidad-tecnologica-nacional\/","title":{"rendered":"OMAR FAURE DESIGNADO COMO SECRETARIO DE CIENCIA Y TECNOLOG\u00cdA DE LA UNIVERSIDAD TECNOL\u00d3GICA NACIONAL."},"content":{"rendered":"\n<p>En el marco de la 6\u00ba Reuni\u00f3n Ordinaria del Consejo Superior, la Universidad Tecnol\u00f3gica Nacional (UTN) realiz\u00f3 el acto de presentaci\u00f3n de sus nuevas autoridades para el per\u00edodo 2025\u20132029. La ceremonia, que fue encabezada por el rector, Ing. Rub\u00e9n Soro.<\/p>\n\n\n\n<p>Durante el encuentro se anunci\u00f3 la conformaci\u00f3n del equipo que acompa\u00f1ar\u00e1 la gesti\u00f3n institucional en las distintas \u00e1reas, consolidando la planificaci\u00f3n estrat\u00e9gica de la Universidad para los pr\u00f3ximos cuatro a\u00f1os.<\/p>\n\n\n\n<p>El  uruguayense Dr. Omar Roberto Faure, de la Facultad Regional Concepci\u00f3n del Uruguay (FRCU) fue designado como Secretario de Ciencia y Tecnolog\u00eda.<\/p>\n\n\n\n<p>A ra\u00edz del nuevo desaf\u00edo, Faure declar\u00f3: \u201cAsumo la designaci\u00f3n como Secretario de Ciencia y Tecnolog\u00eda de la Universidad Tecnol\u00f3gica Nacional, \u00e1mbito desde el cual se definen y articulan las pol\u00edticas de Ciencia y Tecnolog\u00eda para toda la Universidad.Omar inici\u00f3 su trayectoria en la Facultad Regional Concepci\u00f3n del Uruguay en marzo de 2001, donde se desempe\u00f1\u00f3 como docente e investigador, integrando el Grupo de Mec\u00e1nica Computacional y Estructuras (GIMCE).<\/p>\n\n\n\n<p>Adem\u00e1s, expres\u00f3 su agradecimiento: \u201ca la Facultad Regional Concepci\u00f3n del Uruguay, que me ha brindado el espacio para desarrollarme tanto en el plano profesional como humano. Asimismo, agradezco a la gesti\u00f3n del Ing. Herlax, por la confianza depositada en m\u00ed al encomendarme la Secretar\u00eda de Ciencia y T\u00e9cnica de la Facultad, as\u00ed como a mis colegas del GIMCE, con quienes he compartido este recorrido. Y l\u00f3gicamente al rector Ing Ruben Soro por la designaci\u00f3n. Considero este nuevo desaf\u00edo como el m\u00e1s relevante de mi vida profesional.\u201d<\/p>\n\n\n\n<p><strong><em>FORMACI\u00d3N ACAD\u00c9MICA DEL Dr FAURE:<\/em><\/strong><\/p>\n\n\n\n<p><strong><em>Docteur en Sciences Mathematiques<\/em><\/strong><br>UNIVERSITE DE LIEGE (ULG) &#8211; B\u00e9lgica.<br>A\u00f1o de finalizaci\u00f3n: 2000<\/p>\n\n\n\n<p><strong><em>Licenciado en Matematica Aplicada<\/em><\/strong><br>FACULTAD DE INGENIERIA QUIMICA ; UNIVERSIDAD NACIONAL DEL LITORAL<br>A\u00f1o de finalizaci\u00f3n: 07\/1996<\/p>\n\n\n\n<p><strong><em>Universidades en que trabaj\u00f3:<\/em><\/strong><\/p>\n\n\n\n<p>Universidad Tecnol\u00f3gica Nacional. (UTN) distintas Facultades.<\/p>\n\n\n\n<p>Universidad Nacional de Entre Rios.(UNER)<\/p>\n\n\n\n<p>Universidad Nacional del Litoral. (UNL)<\/p>\n\n\n\n<p>Universidad Nacional de San Martin (UNSAM)<\/p>\n\n\n\n<p>Universidad Polit\u00e9cnica de Catalunya<\/p>\n\n\n\n<p>Universidad Aut\u00f3noma de Entre Rios (UADER)<\/p>\n\n\n\n<p>Universidad Nacional de Rosario<\/p>\n\n\n\n<p>Universidad Nacional de Lomas de Zamora<\/p>\n\n\n\n<p>Universidad Nacional de Santiago del Estero.<\/p>\n\n\n\n<p>Evaluador de CONEAU.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el marco de la 6\u00ba Reuni\u00f3n Ordinaria del Consejo Superior, la Universidad Tecnol\u00f3gica Nacional (UTN) realiz\u00f3 el acto de presentaci\u00f3n de sus nuevas autoridades para el per\u00edodo 2025\u20132029. La ceremonia, que fue encabezada por el rector, Ing. Rub\u00e9n Soro. Durante el encuentro se anunci\u00f3 la conformaci\u00f3n del equipo que acompa\u00f1ar\u00e1 la gesti\u00f3n institucional en [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":10736,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"enabled":false},"version":2}},"categories":[176],"tags":[60,1993,3004,2748],"class_list":["post-10735","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion","tag-60","tag-frcu-utn","tag-omar-faure","tag-universidad-tecnologica-nacional"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/3260.com.ar\/web\/wp-content\/uploads\/2025\/12\/UTN-Omar-Faure-scaled.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/3260.com.ar\/web\/wp-json\/wp\/v2\/posts\/10735","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/3260.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/3260.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/3260.com.ar\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/3260.com.ar\/web\/wp-json\/wp\/v2\/comments?post=10735"}],"version-history":[{"count":1,"href":"https:\/\/3260.com.ar\/web\/wp-json\/wp\/v2\/posts\/10735\/revisions"}],"predecessor-version":[{"id":10737,"href":"https:\/\/3260.com.ar\/web\/wp-json\/wp\/v2\/posts\/10735\/revisions\/10737"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/3260.com.ar\/web\/wp-json\/wp\/v2\/media\/10736"}],"wp:attachment":[{"href":"https:\/\/3260.com.ar\/web\/wp-json\/wp\/v2\/media?parent=10735"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/3260.com.ar\/web\/wp-json\/wp\/v2\/categories?post=10735"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/3260.com.ar\/web\/wp-json\/wp\/v2\/tags?post=10735"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}