{"id":4213,"date":"2022-05-31T21:45:17","date_gmt":"2022-06-01T00:45:17","guid":{"rendered":"https:\/\/3260.com.ar\/web\/?p=4213"},"modified":"2022-05-31T21:45:22","modified_gmt":"2022-06-01T00:45:22","slug":"colon-lanza-un-programa-municipal-contra-el-bullying-cyberbullying-y-grooming","status":"publish","type":"post","link":"https:\/\/3260.com.ar\/web\/colon-lanza-un-programa-municipal-contra-el-bullying-cyberbullying-y-grooming\/","title":{"rendered":"Col\u00f3n lanza un programa municipal contra el bullying, cyberbullying y grooming"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La <em>Municipalidad de Col\u00f3n<\/em>, a trav\u00e9s del <em>\u00c1rea de Ni\u00f1ez, Adolescencia y Familia, la Direcci\u00f3n de Cultura y Educaci\u00f3n y la Direcci\u00f3n de Salud<\/em>, coordinan acciones para el<strong> lanzamiento del Programa Municipal de Lucha y Concientizaci\u00f3n Contra el Bullying, Ciberbullying y Grooming.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ese marco, se llevar\u00e1 a cabo en la <em>Casa del Bicentenario<\/em> (<em>Bv. Gaillard 179<\/em>) el pr\u00f3ximo <em>jueves 16 de junio a las 9 <\/em>una <strong>charla que abordar\u00e1 diversos temas que tienen que ver con el cuidado y la salud integral de ni\u00f1os y j\u00f3venes frente a estas problem\u00e1ticas.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El evento contar\u00e1 con la presencia de <em>Silvina Mar\u00eda Calveyra<\/em>, <em>coordinadora del Consejo Provincial de Prevenci\u00f3n, Protecci\u00f3n y Asistencia a V\u00edctimas y Testigos de Trata y Tr\u00e1fico de Personas.<\/em> El programa<em>incluye capacitaciones para docentes y directivos, adem\u00e1s de charlas y talleres para estudiantes de nivel primario y secundario.<\/em><\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Tem\u00e1ticas<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">En las jornadas se abordar\u00e1 la <em>Prevenci\u00f3n y Promoci\u00f3n de los Derechos, los tipos de bullying<\/em> (f\u00edsico, verbal y social), <em>el ciberbullying y su vinculaci\u00f3n con la trata de personas, el bullying en la escuela, la violencia silenciosa en las aulas, el suicidio y las consecuencias en la salud integral de los ni\u00f1os y j\u00f3venes.<\/em><\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\" style=\"font-size:14px\">Fuente: Municipalidad de Col\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Municipalidad de Col\u00f3n, a trav\u00e9s del \u00c1rea de Ni\u00f1ez, Adolescencia y Familia, la Direcci\u00f3n de Cultura y Educaci\u00f3n y la Direcci\u00f3n de Salud, coordinan acciones para el lanzamiento del Programa Municipal de Lucha y Concientizaci\u00f3n Contra el Bullying, Ciberbullying y Grooming. En ese marco, se llevar\u00e1 a cabo en la Casa del Bicentenario (Bv. [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":4214,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"enabled":false},"version":2}},"categories":[176],"tags":[60,582,433,1214],"class_list":["post-4213","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion","tag-60","tag-bullying","tag-colon","tag-grooming"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/3260.com.ar\/web\/wp-content\/uploads\/2022\/05\/bullying-gaf8cd7f3f_1280.png","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/3260.com.ar\/web\/wp-json\/wp\/v2\/posts\/4213","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/3260.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/3260.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/3260.com.ar\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/3260.com.ar\/web\/wp-json\/wp\/v2\/comments?post=4213"}],"version-history":[{"count":0,"href":"https:\/\/3260.com.ar\/web\/wp-json\/wp\/v2\/posts\/4213\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/3260.com.ar\/web\/wp-json\/wp\/v2\/media\/4214"}],"wp:attachment":[{"href":"https:\/\/3260.com.ar\/web\/wp-json\/wp\/v2\/media?parent=4213"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/3260.com.ar\/web\/wp-json\/wp\/v2\/categories?post=4213"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/3260.com.ar\/web\/wp-json\/wp\/v2\/tags?post=4213"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}